{"id":2771,"date":"2016-03-17T18:54:24","date_gmt":"2016-03-17T17:54:24","guid":{"rendered":"http:\/\/www.tirages-pro.com\/blog\/?p=2771"},"modified":"2017-04-16T12:11:18","modified_gmt":"2017-04-16T10:11:18","slug":"calibrez-votre-ecran-en-20-minutes","status":"publish","type":"post","link":"https:\/\/www.tirages-pro.com\/blog\/2016\/03\/calibrez-votre-ecran-en-20-minutes\/","title":{"rendered":"Calibrez votre \u00e9cran en 20 minutes !"},"content":{"rendered":"<p>Pour celui qui veut aller plus loin dans la ma\u00eetrise de sa colorim\u00e9trie, la calibration de son \u00e9cran est une \u00e9tape essentielle. Quelles sont les param\u00e8tres importants ? Les \u00e9tapes d\u00e9cisives ? Quelle sonde utiliser ?\u00a0Toutes les r\u00e9ponses \u00e0 ces questions et bien d&rsquo;autres dans cet article.<!--more--><\/p>\n<h2>Une chaine graphique calibr\u00e9e c&rsquo;est quoi\u00a0?<\/h2>\n<p>Un\u00a0labo professionnel qui se respecte travaille avec des \u00e9crans calibr\u00e9s par ses soins et des couples imprimante\/papiers \u00e9galement calibr\u00e9s par ses soins. C&rsquo;est ce qu&rsquo;on appelle une chaine graphique calibr\u00e9e : les diff\u00e9rents \u00e9l\u00e9ments de la cha\u00eene sont r\u00e9gl\u00e9s sur les m\u00eames bases de couleur et\u00a0la\u00a0luminosit\u00e9 est r\u00e9gl\u00e9e suivant\u00a0les normes.<\/p>\n<p>Ainsi, quand un\u00a0tireur effectue des \u00e9quilibrages ou des retouches sur un de ses \u00e9cran, il est certain que le r\u00e9sultat sur papier sera conforme.<\/p>\n<p>Ne pas s&rsquo;en soucier serait faire du v\u00e9lo avec un guidon mal fix\u00e9 : vous avez l&rsquo;impression de positionner le guidon pr\u00e9cis\u00e9ment, mais la roue fait un peu ce qu&rsquo;elle veut&#8230;<\/p>\n<p>Pour que la chaine calibr\u00e9e soit compl\u00e8te, il ne manque plus qu&rsquo;un \u00e9l\u00e9ment : vous. Le photographe.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-2928 size-medium\" src=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-Sonde-X-rite-i1-Display-Pro-BLOG.jpg?resize=300%2C200&#038;ssl=1\" alt=\"Calibrez votre ecran en 20 minutes - Sonde X-rite i1 Display Pro - BLOG\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-Sonde-X-rite-i1-Display-Pro-BLOG-scaled.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-Sonde-X-rite-i1-Display-Pro-BLOG-scaled.jpg?resize=1020%2C680&amp;ssl=1 1020w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-Sonde-X-rite-i1-Display-Pro-BLOG-scaled.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-Sonde-X-rite-i1-Display-Pro-BLOG-scaled.jpg?resize=2048%2C1366&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<h2>Pourquoi calibrer son \u00e9cran ?<\/h2>\n<p>Soyons clairs, la majorit\u00e9 des photographes qui font appel \u00e0 nos services aujourd&rsquo;hui ne travaillent pas sur \u00e9crans\u00a0calibr\u00e9s. Pourtant, comme le montrent nos rapports d&rsquo;enqu\u00eate apr\u00e8s commande, ils sont satisfaits \u00e0 99.56\u00a0% !<\/p>\n<p>La calibration de son \u00e9cran n&rsquo;est donc pas une n\u00e9cessit\u00e9 pour obtenir un bon r\u00e9sultat avec son labo. Par contre, pour\u00a0un investissement modeste, elle vous donnera une s\u00e9curit\u00e9 de r\u00e9sultat tr\u00e8s appr\u00e9ciable.<\/p>\n<p>De notre point de vue (ind\u00e9pendant), il existe 2 sondes convenables pour un budget raisonnable. Elles sont toutes les 2 fabriqu\u00e9es par la marque X-rite.<\/p>\n<ul>\n<li>X-rite i1\u00a0Display Pro\u00a0(environ 220\u00a0\u20ac en mars 2016) \u2014 <a href=\"http:\/\/www.amazon.fr\/gp\/product\/B0055MBQOW\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;tag=tirag00-21&amp;creativeASIN=B0055MBQOW&amp;linkCode=as2\" target=\"_blank\">Voir sur Amazon \u00bb<\/a><\/li>\n<li>X-rite Color Munki Display (environ 149 \u20ac en mars 2016) \u2014 <a href=\"http:\/\/www.amazon.fr\/gp\/product\/B0055MBQOM\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;tag=tirag00-21&amp;creativeASIN=B0055MBQOM&amp;linkCode=as2\" target=\"_blank\">Voir sur Amazon \u00bb<\/a><\/li>\n<\/ul>\n<p>Les deux solutions utilisent le m\u00eame capteur mais le logiciel de la version moins cher est brid\u00e9. La mesure est plus lente et vous n&rsquo;aurez le choix qu&rsquo;entre 5000 \u00b0K, 5500 \u00b0K et 6500\u00b0K. Si vous le pouvez, nous vous conseillons donc la sonde\u00a0X-rite\u00a0i1\u00a0Display Pro. C&rsquo;est\u00a0un excellent compromis qualit\u00e9 \/ prix.<\/p>\n<p>C&rsquo;est donc logiquement cette sonde que nous allons utiliser dans le reste de cet article. Nous avons choisi le mode \u00ab\u00a0avanc\u00e9\u00a0\u00bb\u00a0qui permet un niveau de contr\u00f4le plus \u00e9lev\u00e9 et des r\u00e9sultats potentiellement plus pr\u00e9cis.<\/p>\n<h2>La sonde X-Rite i1 Display Pro<\/h2>\n<h3>Unboxing<\/h3>\n<p>Voici le contenu de la bo\u00eete :<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2856\" src=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/02\/Calibrez-votre-ecran-en-20-minutes-Contenu-de-la-boite-BLOG.jpg?resize=600%2C400&#038;ssl=1\" alt=\"Calibrez votre ecran en 20 minutes - Contenu de la boite - BLOG\" width=\"600\" height=\"400\" srcset=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/02\/Calibrez-votre-ecran-en-20-minutes-Contenu-de-la-boite-BLOG-scaled.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/02\/Calibrez-votre-ecran-en-20-minutes-Contenu-de-la-boite-BLOG-scaled.jpg?resize=1020%2C680&amp;ssl=1 1020w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/02\/Calibrez-votre-ecran-en-20-minutes-Contenu-de-la-boite-BLOG-scaled.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/02\/Calibrez-votre-ecran-en-20-minutes-Contenu-de-la-boite-BLOG-scaled.jpg?resize=2048%2C1365&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<h3>Le logiciel i1Profiler<\/h3>\n<p>Une fois le logiciel i1Profiler install\u00e9 (en t\u00e9l\u00e9chargeant de pr\u00e9f\u00e9rence la derni\u00e8re version sur le site X-rite), vous pouvez lancer le logiciel et brancher la sonde.<\/p>\n<p><i>Note : Nous vous recommandons d\u2019enregistrer votre produit aupr\u00e8s d\u2019X-Rite en cr\u00e9ant un compte au moyen du bouton \u00ab\u00a0Inscription\u00a0\u00bb. Certains utilisateurs ayant constat\u00e9 que dans certains cas seul le mode demo du logiciel \u00e9tait utilisable, pour une p\u00e9riode de 30 jours. Le num\u00e9ro de s\u00e9rie n\u00e9cessaire \u00e0 l\u2019enregistrement figure sur l\u2019\u00e9tiquette du contrepoids. La licence du logiciel \u00e9tant conditionn\u00e9e \u00e0 votre mat\u00e9riel, si votre sonde n\u2019est pas branch\u00e9e, iProfiler restera en mode demo.<\/i><\/p>\n<p>Cette formalit\u00e9 accomplie, l\u2019ensemble des licences autoris\u00e9es pour votre mat\u00e9riel est donc affich\u00e9 \u00e0 l\u2019\u00e9cran comme ci-dessous selon le mode utilisateur choisi :<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-de-demarrage-BLOG.jpg?ssl=1\" rel=\"attachment wp-att-2914\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2914\" src=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-de-demarrage-BLOG.jpg?resize=600%2C342&#038;ssl=1\" alt=\"Calibrez votre ecran en 20 minutes - i1profiler - Ecran de demarrage - BLOG\" width=\"600\" height=\"342\" srcset=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-de-demarrage-BLOG.jpg?resize=300%2C171&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-de-demarrage-BLOG.jpg?resize=1536%2C876&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-de-demarrage-BLOG.jpg?resize=1024%2C584&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-de-demarrage-BLOG.jpg?w=1954&amp;ssl=1 1954w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>D\u00e8s lors il ne vous reste plus qu\u2019\u00e0 s\u00e9lectionner le bouton \u00ab\u00a0Caract\u00e9risation\u00a0\u00bb sous le titre \u00ab\u00a0Affichage\u00a0\u00bb dans la barre lat\u00e9rale afin de d\u00e9marrer le processus de calibration de votre moniteur.<\/p>\n<p>Le menu du logiciel d\u00e9di\u00e9 i1Profiler d\u00e9tecte alors le\u00a0ou les \u00e9crans connect\u00e9s. Dans notre cas il s\u2019agit d\u2019un moniteur DELL connect\u00e9 \u00e0 un Apple\u00a0MacBook Pro. Il vous suffit maintenant de s\u00e9lectionner le moniteur que vous souhaitez \u00e9talonner. Afin de vous \u00e9viter des torticolis inutiles, le logiciel positionnera alors la fen\u00eatre de iProfiler sur l\u2019\u00e9cran concern\u00e9 pour le reste de la proc\u00e9dure.<\/p>\n<h4>\u00c9cran\u00a01 &#8211; Param\u00e8tres de l\u2019\u00e9cran<\/h4>\n<p>Voici les param\u00e8tres que nous vous conseillons:<\/p>\n<ul>\n<li>Luminance\u00a0: <strong>120 cd\/m<sup>2<\/sup><\/strong><\/li>\n<li>Point blanc : <strong>5785 \u00b0K<\/strong><\/li>\n<li>Gamma : <strong>2.2 (natif)<\/strong><\/li>\n<li>Rapport de contraste : <strong>Natif<\/strong> (contraste maximum de l&rsquo;\u00e9cran) ou bien\u00a0<strong>PCS ICC 287:1<\/strong>\u00a0si vous ne vous servez de votre \u00e9cran que pour imprimer.<\/li>\n<\/ul>\n<ul>\n<li>Enfin, compte tenu de l\u2019environnement de nos \u00e9crans \u00e0 calibrer, nous avons d\u00e9sactiv\u00e9 l\u2019option \u00ab\u00a0Flare Correct\u00a0\u00bb (correction du profil d\u2019affichage en fonction des lumi\u00e8res parasites d\u00e9tect\u00e9es) laquelle s\u2019av\u00e9rait inutile pour nous. La fonction relative \u00e0 la correction du profil en fonction de l\u2019\u00e9clairage ambiant a \u00e9galement \u00e9t\u00e9 d\u00e9sactiv\u00e9e et fera l\u2019objet de tests ult\u00e9rieurs afin de vous proposer un retour d\u2019exp\u00e9rience pr\u00e9cis.<\/li>\n<\/ul>\n<p>La copie d\u2019\u00e9cran ci-dessous r\u00e9capitule l\u2019ensemble des options retenues sur cette fen\u00eatre :<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-1-BLOG.jpg?ssl=1\" rel=\"attachment wp-att-2915\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2915\" src=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-1-BLOG.jpg?resize=600%2C342&#038;ssl=1\" alt=\"Calibrez votre ecran en 20 minutes - i1profiler - Ecran 1 - BLOG\" width=\"600\" height=\"342\" srcset=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-1-BLOG.jpg?resize=300%2C171&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-1-BLOG.jpg?resize=1536%2C876&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-1-BLOG.jpg?resize=1024%2C584&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-1-BLOG.jpg?w=1954&amp;ssl=1 1954w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Avant de passer \u00e0 l\u2019\u00e9cran suivant, et de poursuivre le processus de calibration, vous pouvez enregistrer vos param\u00e8tres ainsi pr\u00e9-r\u00e9gl\u00e9s, afin de gagner du temps lors d\u2019une prochaine calibration, ou afin de comparer la variation \u00e9ventuelle des r\u00e9sultats obtenus en fonction des options choisies.<\/p>\n<h4>\u00c9cran\u00a02 &#8211; Param\u00e8tres des profils<\/h4>\n<p>Sur cette fen\u00eatre, nous avons choisi de d\u00e9sactiver l\u2019utilisation des param\u00e8tres par d\u00e9fauts, surtout afin de changer la version du profil ICC. En effet, le logiciel vous donne l\u2019acc\u00e8s \u00e0 la version 2 et la version 4, cette derni\u00e8re \u00e9tant s\u00e9lectionn\u00e9e par d\u00e9faut.<\/p>\n<p>Les autres r\u00e9glages propos\u00e9s ne sont pas modifi\u00e9s : adaptation chromatique par d\u00e9faut (Bradford) et type de profil bas\u00e9 sur une matrice.<\/p>\n<p>La copie d\u2019\u00e9cran ci-dessous r\u00e9capitule l\u2019ensemble des options retenues :<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-2-BLOG.jpg?ssl=1\" rel=\"attachment wp-att-2917\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2917\" src=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-2-BLOG.jpg?resize=600%2C342&#038;ssl=1\" alt=\"Calibrez votre ecran en 20 minutes - i1profiler - Ecran 2 - BLOG\" width=\"600\" height=\"342\" srcset=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-2-BLOG.jpg?resize=300%2C171&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-2-BLOG.jpg?resize=1536%2C876&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-2-BLOG.jpg?resize=1024%2C584&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-2-BLOG.jpg?w=1954&amp;ssl=1 1954w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Tout comme sur la fen\u00eatre pr\u00e9c\u00e9dente, vous pouvez l\u00e0 aussi enregistrer vos pr\u00e9-r\u00e9glages avant de passer au panneau suivant.<\/p>\n<h4>\u00c9cran\u00a03 &#8211; Jeu de patchs<\/h4>\n<p>Cette fen\u00eatre vous permettra de d\u00e9terminer le nombre de matchs de couleur que vous souhaitez utiliser lors de votre test de calibration. Autrement dit, c\u2019est le nombre de couleurs diff\u00e9rentes que l\u2019\u00e9cran fera d\u00e9filer devant le capteur de la\u00a0sonde.<\/p>\n<p>Le logiciel vous propose 3 tailles de jeux de patchs, respectivement compos\u00e9s de 118, 211, 462 \u00e9chantillons de couleurs. Comme vous pouvez l&rsquo;imaginer, nous vous conseillons choisir\u00a0le plus grand jeu de patchs.<\/p>\n<p>La copie d\u2019\u00e9cran ci-dessous r\u00e9capitule l\u2019ensemble des options retenues :<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-3-BLOG.jpg?ssl=1\" rel=\"attachment wp-att-2918\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2918\" src=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-3-BLOG.jpg?resize=600%2C342&#038;ssl=1\" alt=\"Calibrez votre ecran en 20 minutes - i1profiler - Ecran 3 - BLOG\" width=\"600\" height=\"342\" srcset=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-3-BLOG.jpg?resize=300%2C171&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-3-BLOG.jpg?resize=1536%2C876&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-3-BLOG.jpg?resize=1024%2C584&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-3-BLOG.jpg?w=1954&amp;ssl=1 1954w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<h4>\u00c9cran\u00a04 &#8211; Mesure<\/h4>\n<p>Cette fen\u00eatre est la derni\u00e8re \u00e0 laquelle vous avez acc\u00e8s avant de lancer la mesure. Le logiciel vous y indique que l\u2019instrument de mesure est branch\u00e9 et pr\u00eat \u00e0 \u00eatre utilis\u00e9.<\/p>\n<p>La seule option que vous pouvez choisir ici consiste \u00e0 r\u00e9gler vous m\u00eame la luminosit\u00e9, le contraste et les gains RVB ou \u00e0 l\u2019inverse de laisser le logiciel contr\u00f4ler cela pour vous de fa\u00e7on automatique via la fonction ADC (Automatic Display Control). Cette fonction permet d\u2019automatiser le r\u00e9glage de votre moniteur de mani\u00e8re \u00e0 acc\u00e9l\u00e9rer le processus de calibration, \u00e9viter les r\u00e9glages manuels et garantir des r\u00e9sultats optimaux.<\/p>\n<p>La copie d\u2019\u00e9cran ci-dessous r\u00e9capitule l\u2019ensemble des options retenues :<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-4-BLOG.jpg?ssl=1\" rel=\"attachment wp-att-2919\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2919\" src=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-4-BLOG.jpg?resize=600%2C342&#038;ssl=1\" alt=\"Calibrez votre ecran en 20 minutes - i1profiler - Ecran 4 - BLOG\" width=\"600\" height=\"342\" srcset=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-4-BLOG.jpg?resize=300%2C171&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-4-BLOG.jpg?resize=1536%2C876&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-4-BLOG.jpg?resize=1024%2C584&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-4-BLOG.jpg?w=1954&amp;ssl=1 1954w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Appuyez sur \u00ab\u00a0D\u00e9marrer la mesure\u00a0\u00bb et suivez les\u00a0indications \u00e0 l\u2019\u00e9cran :<\/p>\n<ol>\n<li>en pla\u00e7ant la sonde au centre de l\u2019\u00e9cran pour lancer la mesure<\/li>\n<li>en posant la sonde devant l\u2019\u00e9cran avec le filtre de lumi\u00e8re ambiante<\/li>\n<\/ol>\n<p>Apr\u00e8s 7 \u00e0 8 minutes, le logiciel affiche la derni\u00e8re fen\u00eatre : il ne vous reste plus alors qu\u2019\u00e0 cr\u00e9er \/ enregistrer votre profil ICC.<\/p>\n<h4>\u00c9cran 5 &#8211; Profil ICC<\/h4>\n<p>Sur cet \u00e9cran, le logiciel vous affiche le compte-rendu de la calibration et vous propose de nommer et enregistrer votre profil ICC.<\/p>\n<p>Nous vous conseillons d\u2019activer la fonction \u00ab\u00a0Rappel de caract\u00e9risation\u00a0\u00bb afin de ne pas oublier de tester votre ou vos \u00e9crans \u00e0 fr\u00e9quence constante (toutes les 4 semaines dans ce test). Cette fr\u00e9quence d\u00e9pend naturellement de la qualit\u00e9 de votre \u00e9cran, mais \u00e9galement de l\u2019utilisation que vous en faites. Si vous constatez qu\u2019entre deux mesures la variation de profil est importante, il faudra envisager de resserrer la fr\u00e9quence de calibration.<\/p>\n<p>Enfin, si vous avez activ\u00e9 la fonction \u00ab\u00a0Contr\u00f4le de l\u2019\u00e9clairage ambiant\u00a0\u00bb, vous aurez la possibilit\u00e9 de param\u00e9trer cette fr\u00e9quence de ce contr\u00f4le (jusqu\u2019\u00e0 60 minutes au maximum) ainsi que la notification (ou non) en cas d\u2019ajustement automatique des valeurs d\u2019affichage.<\/p>\n<p>Nous n\u2019avons pas souhait\u00e9 activer cette fonction qui nous semble inappropri\u00e9e aux conditions d\u2019utilisation de nos moniteurs.<\/p>\n<p>La copie d\u2019\u00e9cran ci-dessous r\u00e9capitule l\u2019ensemble des options retenues :<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-5-BLOG.jpg?ssl=1\" rel=\"attachment wp-att-2920\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2920\" src=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-5-BLOG.jpg?resize=600%2C342&#038;ssl=1\" alt=\"Calibrez votre ecran en 20 minutes - i1profiler - Ecran 5 - BLOG\" width=\"600\" height=\"342\" srcset=\"https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-5-BLOG.jpg?resize=300%2C171&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-5-BLOG.jpg?resize=1536%2C876&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-5-BLOG.jpg?resize=1024%2C584&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tirages-pro.com\/blog\/wp-content\/uploads\/2016\/03\/Calibrez-votre-ecran-en-20-minutes-i1profiler-Ecran-5-BLOG.jpg?w=1954&amp;ssl=1 1954w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Cliquez sur le bouton \u00ab\u00a0Cr\u00e9er et enregistrer le profil\u00a0\u00bb : \u00e7a y est, votre \u00e9cran est calibr\u00e9 !<\/p>\n<p>Enfin, si vous souhaitiez gagner du temps \u00e0 chaque calibration, X-Rite a pens\u00e9 \u00e0 vous et vous permet d\u2019enregistrer la proc\u00e9dure\u00a0via un bouton d\u00e9di\u00e9 qui vous permettra, au lancement du logiciel iProfiler, de r\u00e9p\u00e9ter l\u2019ensemble des \u00e9tapes du processus de calibration\u2026 d\u2019un simple clic en choisissant d\u00e8s le d\u00e9marrage l\u2019option \u00ab\u00a0Charger la proc\u00e9dure\u00a0\u00bb.<\/p>\n<p>Donc, au final, si l\u2019on compte :<\/p>\n<ul>\n<li>10 minutes pour param\u00e9trer l\u2019ensemble des panneaux de configuration ;<\/li>\n<li>7 \u00e0 8 minutes pour l\u2019analyse des 468 patchs color\u00e9s ;<\/li>\n<li>2 minutes pour la cr\u00e9ation et l\u2019application de votre profil ICC<\/li>\n<\/ul>\n<p>Votre \u00e9cran peut \u00eatre calibr\u00e9 en moins de 20 minutes et pour environ\u00a0220 \u20ac. De quoi vous faire gagner du temps en \u00e9dition de vos images, et vous tranquilliser quant \u00e0 l\u2019obtention de tirages fid\u00e8les \u00e0 votre rendu \u00e9cran. \u00c0 vous de jouer !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour celui qui veut aller plus loin dans la ma\u00eetrise de sa colorim\u00e9trie, la calibration de son \u00e9cran est une \u00e9tape essentielle. Quelles sont les param\u00e8tres importants ? Les \u00e9tapes d\u00e9cisives ? Quelle sonde utiliser ?\u00a0Toutes les r\u00e9ponses \u00e0 ces questions et bien d&rsquo;autres dans cet article.<\/p>\n","protected":false},"author":7,"featured_media":2859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","inline_featured_image":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[4],"tags":[39,166,165,164,163,217,168,162,167],"class_list":["post-2771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutoriels","tag-calibration","tag-caracterisation","tag-colorimetrie","tag-couleur","tag-ecran","tag-featured","tag-i1display-pro","tag-sonde","tag-xrite"],"_links":{"self":[{"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/posts\/2771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/comments?post=2771"}],"version-history":[{"count":21,"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/posts\/2771\/revisions"}],"predecessor-version":[{"id":2938,"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/posts\/2771\/revisions\/2938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/media\/2859"}],"wp:attachment":[{"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/media?parent=2771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/categories?post=2771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tirages-pro.com\/blog\/wp-json\/wp\/v2\/tags?post=2771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}